{"id":26001,"date":"2023-06-06T09:48:31","date_gmt":"2023-06-06T07:48:31","guid":{"rendered":"https:\/\/www.pomgedichten.nl\/?p=26001"},"modified":"2023-06-06T09:48:32","modified_gmt":"2023-06-06T07:48:32","slug":"ien-verrips-over-missen-het-kind-waarnaar-je-lang-verlangde-maar-ongeboren-bleef","status":"publish","type":"post","link":"https:\/\/www.pomgedichten.nl\/index.php\/2023\/06\/06\/ien-verrips-over-missen-het-kind-waarnaar-je-lang-verlangde-maar-ongeboren-bleef\/","title":{"rendered":"IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;"},"content":{"rendered":"\n<p><em>het kind waarnaar je lang verlangde\u00a0<br>maar ongeboren bleef<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2023\/04\/ienverrips0-rotated.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2023\/04\/ienverrips0-rotated.jpg\" alt=\"\" class=\"wp-image-25560\" srcset=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2023\/04\/ienverrips0-rotated.jpg 480w, https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2023\/04\/ienverrips0-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><figcaption class=\"wp-element-caption\"><br>kun je missen wat je niet hebt<br>nooit hebt gehad<br>het hondje dat je zo graag wou als kind\u00a0<br>maar je ouders zeiden nee<br>kun je degene missen met wie je wilde leven<br>maar die je nooit ontmoette<br>het kind waarnaar je lang verlangde\u00a0<br>maar ongeboren bleef<br>kun je nu al morgen missen\u00a0<br>de toekomst die de jouwe niet zal zijn<br>kun je de woorden missen\u00a0<br>ongeschreven ongezegd <br><br>Ien Verrips<br><\/figcaption><\/figure>\n<\/div>\r\n\t\t<style>\r\n\t\t\t.huge-it-share-buttons {\r\n\t\t\t\tborder:0px solid #0FB5D6;\r\n\t\t\t\tborder-radius:5px;\r\n\t\t\t\tbackground:#3BD8FF;\r\n\t\t\t\t\t\t text-align:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t#huge-it-share-buttons-top {margin-bottom:0px;}\r\n\t\t\t#huge-it-share-buttons-bottom {margin-top:0px;}\r\n\r\n\t\t\t.huge-it-share-buttons h3 {\r\n\t\t\t\tfont-size:25px ;\r\n\t\t\t\tfont-family:Arial,Helvetica Neue,Helvetica,sans-serif;\r\n\t\t\t\tcolor:#666666;\r\n\r\n\t\t\tdisplay:block;\t\t\t\tline-height:25px ;\r\n\r\n\t\t\t\t\t\t text-align:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul {\r\n\t\t\t\t\t\t float:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul li {\r\n\t\t\t\tmargin-left:3px;\r\n\t\t\t\tmargin-right:3px;\r\n\t\t\t\tpadding:0px;\r\n\t\t\t\tborder:0px ridge #E6354C;\r\n\t\t\t\tborder-radius:11px;\r\n\t\t\t\tbackground-color:#14CC9B;\r\n\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul li #backforunical26001 {\r\n\t\t\t\tborder-bottom: 0;\r\n\t\t\t\tbackground-image:url('https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/buttons.20.png');\r\n\t\t\t\twidth:20px;\r\n\t\t\t\theight:20px;\r\n\t\t\t}\r\n\r\n\t\t\t.front-shares-count {\r\n\t\t\t\tposition: absolute;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\tdisplay: block;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size20 .front-shares-count {\r\n\t\t\t\tfont-size: 10px;\r\n\t\t\t\ttop: 10px;\r\n\t\t\t\twidth: 20px;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size30 .front-shares-count {\r\n\t\t\t\tfont-size: 11px;\r\n\t\t\t\ttop: 15px;\r\n\t\t\t\twidth: 30px;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size40 .front-shares-count {\r\n\t\t\t\tfont-size: 12px;\r\n\t\t\t\ttop: 21px;\r\n\t\t\t\twidth: 40px;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t\r\n\t\t<div id=\"huge-it-share-buttons-top\" class=\"huge-it-share-buttons nobackground\">\r\n\t\t\t<h3>Share This:<\/h3>\r\n\t\t\t<ul class=\"huge-it-share-buttons-list \">\r\n\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('https:\/\/www.facebook.com\/sharer\/sharer.php?u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -0px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/twitter.com\/share?status=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&text=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('https:\/\/twitter.com\/share?status=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&text=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -20px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/www.pinterest.com\/pin\/create\/button\/?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&media=https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/www.pinterest.com\/pin\/create\/button\/?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&media=https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -40px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/plus.google.com\/share?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('https:\/\/plus.google.com\/share?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -60px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/www.linkedin.com\/shareArticle?title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;&mini=true&url=https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('https:\/\/www.linkedin.com\/shareArticle?title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;&mini=true&url=https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -80px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/www.tumblr.com\/share\/link?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&name=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('https:\/\/www.tumblr.com\/share\/link?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&name=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -100px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/digg.com\/submit?phase=2&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/digg.com\/submit?phase=2&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -120px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/www.stumbleupon.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/www.stumbleupon.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -140px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/myspace.com\/post?l=3&u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('https:\/\/myspace.com\/post?l=3&u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -160px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/vk.com\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/vk.com\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -180px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/www.reddit.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/www.reddit.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -200px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/www.bebo.com\/c\/share?Url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('http:\/\/www.bebo.com\/c\/share?Url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -220px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"https:\/\/delicious.com\/save?v=5&noui&jump=close&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('https:\/\/delicious.com\/save?v=5&noui&jump=close&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -240px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\"  onclick=\"javascript:void window.open('http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -260px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -280px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/service.weibo.com\/share\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&appkey=&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;&pic=&ralateUid=&\"  onclick=\"javascript:void window.open('http:\/\/service.weibo.com\/share\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&appkey=&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;&pic=&ralateUid=&','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -300px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/widget.renren.com\/dialog\/share?resourceUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&srcUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/widget.renren.com\/dialog\/share?resourceUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&srcUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -320px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical26001\" href=\"http:\/\/n4g.com\/tips?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;\"  onclick=\"javascript:void window.open('http:\/\/n4g.com\/tips?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001&title=IEN VERRIPS over missen: &#8216;het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef&#8230;&#8217;','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -340px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t<div class=\"clear\"><\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>het kind waarnaar je lang verlangde\u00a0maar ongeboren bleef Share This:<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26001","post","type-post","status-publish","format-standard","hentry","category-pomberichten","entry"],"_links":{"self":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/comments?post=26001"}],"version-history":[{"count":1,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\/revisions"}],"predecessor-version":[{"id":26002,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/26001\/revisions\/26002"}],"wp:attachment":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/media?parent=26001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/categories?post=26001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/tags?post=26001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}