{"id":35210,"date":"2026-09-01T00:16:00","date_gmt":"2026-08-31T22:16:00","guid":{"rendered":"https:\/\/www.pomgedichten.nl\/?p=35210"},"modified":"2026-08-31T21:42:47","modified_gmt":"2026-08-31T19:42:47","slug":"afwisseling-van-de-poetische-wacht-dank-je-wel-ali-serik-welkom-terug-peter-posthumus","status":"publish","type":"post","link":"https:\/\/www.pomgedichten.nl\/index.php\/2026\/09\/01\/afwisseling-van-de-poetische-wacht-dank-je-wel-ali-serik-welkom-terug-peter-posthumus\/","title":{"rendered":"afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"749\" src=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman-1024x749.png\" alt=\"\" class=\"wp-image-35088\" style=\"aspect-ratio:1.3671822698284064;width:438px;height:auto\" srcset=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman-1024x749.png 1024w, https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman-300x220.png 300w, https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman-768x562.png 768w, https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/08\/Fred-Hopman.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>foto: Fred Hopman<\/em><br><em>Beste Pom,<br>Het was voor mij een groot genoegen om als gastdichter op je website te mogen staan. Hartelijk dank voor de waardering voor mijn gedichten.<\/em><br><br><strong>Ik wil Ali van harte bedanken voor het zomer gastdichterschap dat hij de afgelopen weken op &#8216;de pom&#8217; vervulde &#8211; de mooie gedichten die hij de lezers van deze site heeft aangeboden &#8211; bijzondere po\u00ebzie, raak en met taalkracht de woorden &#8211;  vandaag de laatste &#8211; dank je wel!<\/strong><br><br><br><strong>Boekhouders<\/strong><br><br>Er is geen jaargetijde voor het instorten van huizen.<br>Je hebt altijd wel vrouwen met grote handen,<br>die tegen een muur van andermans huis geleund zitten,<br>hun vijand vervloeken, met al hun pijn.<br><br>Mannen die maar blijven lopen, als dolle dieren<br>rond hun neergekletterde dromen.<br>Niet weten wat ze moeten doen om hun wanhoop te dragen,<br>alleen dat ze het puin moeten ruimen.<br><br>Gelukkig heb je overal kinderen,<br>ze vergeten het ene en onthouden het andere.<br>Ze bouwen hutten met afval, voor hun speelgoed<br>dat ze terugvinden, ontsnapt uit de verwoesting.<br><br>Dan heb je nog katten en honden, ze begrijpen<br>niets van bankbiljetten en vergroeide belangen.<br>Kijken net als alle anderen naar de hemel,<br>maar blijven zoeken naar hun voerbak.<br><br>Als laatste heb je de plunderaars, in wezen<br>zijn ze ons geweten, aanbidden dezelfde god,<br>kijken graag weg als anderen lijden.<br>Ze zijn de boekhouders van de mensheid.<br><br>Ali \u015eerik<br><\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/05\/697792841_10242661501943934_1267228316395782065_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/05\/697792841_10242661501943934_1267228316395782065_n.jpg\" alt=\"\" class=\"wp-image-34366\" style=\"width:386px;height:auto\" srcset=\"https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/05\/697792841_10242661501943934_1267228316395782065_n.jpg 720w, https:\/\/www.pomgedichten.nl\/wp-content\/uploads\/2026\/05\/697792841_10242661501943934_1267228316395782065_n-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Hoi Pom,Morgen is het alweer september, ik zou wel weer twee wekelijks willen bijdragen, vandaar deze korte meditatie bij de hier zowat voorbije zomer:<\/em> <br><br><strong>welkom terug Peter &#8211; jouw tweewekelijkse bijdrage heel graag aanvaard &#8211; de dinsdagen afwisselend met de po\u00ebzie van  Ien Verrips &#8211; <\/strong><br><br><br>Wat een zomer, zo veel zon<br>en nauwelijks een druppel<br>wat prachtig weer<br><br>naar buiten, de snelweg op<br>naar het platteland<br>genieten van het geronk der machines, het fijnstof en het gif<br>zelf de laatste vogels zien<br>op zoek naar de restanten aan<br>oorspronkelijk leven want:<br>&#8221; wat is natuur nog in dit land<br>een stukje bos ter grootte van een krant &#8221; *)<br><br>de snelweg op, naar de steden<br>een zomer vol tractorende boeren<br>heel deftig onder politie begeleiding<br>en er vielen doden<br>onder het al oude ( fascistische ) adagium:<br>waar gehakt wordt vallen spaanders<br><br>wat een zomer, dat medeleven<br>die warmte, wie wil dat niet<br><br><br>Peter Posthumus<br><br><em>*) J.C. Bloem<\/em><\/figcaption><\/figure>\n<\/div>\r\n\t\t<style>\r\n\t\t\t.huge-it-share-buttons {\r\n\t\t\t\tborder:0px solid #0FB5D6;\r\n\t\t\t\tborder-radius:5px;\r\n\t\t\t\tbackground:#3BD8FF;\r\n\t\t\t\t\t\t text-align:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t#huge-it-share-buttons-top {margin-bottom:0px;}\r\n\t\t\t#huge-it-share-buttons-bottom {margin-top:0px;}\r\n\r\n\t\t\t.huge-it-share-buttons h3 {\r\n\t\t\t\tfont-size:25px ;\r\n\t\t\t\tfont-family:Arial,Helvetica Neue,Helvetica,sans-serif;\r\n\t\t\t\tcolor:#666666;\r\n\r\n\t\t\tdisplay:block;\t\t\t\tline-height:25px ;\r\n\r\n\t\t\t\t\t\t text-align:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul {\r\n\t\t\t\t\t\t float:right; \t\t\t\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul li {\r\n\t\t\t\tmargin-left:3px;\r\n\t\t\t\tmargin-right:3px;\r\n\t\t\t\tpadding:0px;\r\n\t\t\t\tborder:0px ridge #E6354C;\r\n\t\t\t\tborder-radius:11px;\r\n\t\t\t\tbackground-color:#14CC9B;\r\n\t\t\t}\r\n\r\n\t\t\t.huge-it-share-buttons ul li #backforunical35210 {\r\n\t\t\t\tborder-bottom: 0;\r\n\t\t\t\tbackground-image:url('https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/buttons.20.png');\r\n\t\t\t\twidth:20px;\r\n\t\t\t\theight:20px;\r\n\t\t\t}\r\n\r\n\t\t\t.front-shares-count {\r\n\t\t\t\tposition: absolute;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\tdisplay: block;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size20 .front-shares-count {\r\n\t\t\t\tfont-size: 10px;\r\n\t\t\t\ttop: 10px;\r\n\t\t\t\twidth: 20px;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size30 .front-shares-count {\r\n\t\t\t\tfont-size: 11px;\r\n\t\t\t\ttop: 15px;\r\n\t\t\t\twidth: 30px;\r\n\t\t\t}\r\n\r\n\t\t\t.shares_size40 .front-shares-count {\r\n\t\t\t\tfont-size: 12px;\r\n\t\t\t\ttop: 21px;\r\n\t\t\t\twidth: 40px;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t\r\n\t\t<div id=\"huge-it-share-buttons-top\" class=\"huge-it-share-buttons nobackground\">\r\n\t\t\t<h3>Share This:<\/h3>\r\n\t\t\t<ul class=\"huge-it-share-buttons-list \">\r\n\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('https:\/\/www.facebook.com\/sharer\/sharer.php?u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -0px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/twitter.com\/share?status=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&text=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('https:\/\/twitter.com\/share?status=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&text=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -20px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/www.pinterest.com\/pin\/create\/button\/?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&media=https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/www.pinterest.com\/pin\/create\/button\/?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&media=https:\/\/www.pomgedichten.nl\/wp-content\/plugins\/wp-share-buttons\/Front_end\/..\/images\/noimage.png&description=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -40px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/plus.google.com\/share?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('https:\/\/plus.google.com\/share?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -60px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/www.linkedin.com\/shareArticle?title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus&mini=true&url=https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('https:\/\/www.linkedin.com\/shareArticle?title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus&mini=true&url=https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -80px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/www.tumblr.com\/share\/link?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&name=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('https:\/\/www.tumblr.com\/share\/link?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&name=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -100px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/digg.com\/submit?phase=2&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/digg.com\/submit?phase=2&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -120px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/www.stumbleupon.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/www.stumbleupon.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -140px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/myspace.com\/post?l=3&u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('https:\/\/myspace.com\/post?l=3&u=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -160px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/vk.com\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/vk.com\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -180px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/www.reddit.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/www.reddit.com\/submit?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -200px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/www.bebo.com\/c\/share?Url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('http:\/\/www.bebo.com\/c\/share?Url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -220px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"https:\/\/delicious.com\/save?v=5&noui&jump=close&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('https:\/\/delicious.com\/save?v=5&noui&jump=close&url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -240px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\"  onclick=\"javascript:void window.open('http:\/\/www.odnoklassniki.ru\/dk?st.cmd=addShare&st.s=2&st.noresize=on&st._surl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -260px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/sns.qzone.qq.com\/cgi-bin\/qzshare\/cgi_qzshare_onekey?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -280px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/service.weibo.com\/share\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&appkey=&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus&pic=&ralateUid=&\"  onclick=\"javascript:void window.open('http:\/\/service.weibo.com\/share\/share.php?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&appkey=&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus&pic=&ralateUid=&','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -300px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/widget.renren.com\/dialog\/share?resourceUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&srcUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/widget.renren.com\/dialog\/share?resourceUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&srcUrl=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -320px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t<li class=\"none nobackground \" >\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a id=\"backforunical35210\" href=\"http:\/\/n4g.com\/tips?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus\"  onclick=\"javascript:void window.open('http:\/\/n4g.com\/tips?url=www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210&title=afwisseling van de po\u00ebtische wacht &#8211; dank je wel Ali \u015eerik &#8211; welkom terug Peter Posthumus','1410949501326','width=700,height=500,toolbar=0,menubar=0,location=0,status=1,scrollbars=1,resizable=1,left=0,top=0');return false;\" style=\"background-position: -340px -80px \"><\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t<div class=\"clear\"><\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Share This:<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1],"tags":[185,32],"class_list":["post-35210","post","type-post","status-publish","format-standard","hentry","category-pomberichten","tag-ali-serik","tag-peterposthumus","entry"],"_links":{"self":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/comments?post=35210"}],"version-history":[{"count":1,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\/revisions"}],"predecessor-version":[{"id":35211,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/posts\/35210\/revisions\/35211"}],"wp:attachment":[{"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/media?parent=35210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/categories?post=35210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pomgedichten.nl\/index.php\/wp-json\/wp\/v2\/tags?post=35210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}